{"id":102,"date":"2019-08-27T17:00:44","date_gmt":"2019-08-27T15:00:44","guid":{"rendered":"http:\/\/wp12274780.server-he.de\/TIMM\/?page_id=102"},"modified":"2020-11-30T13:52:47","modified_gmt":"2020-11-30T12:52:47","slug":"alle-referenzen","status":"publish","type":"page","link":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/referenzen\/alle-referenzen\/","title":{"rendered":"Alle Referenzen"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; bg_image=&#8220;35&#8243; bg_position=&#8220;center center&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;400&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text css=&#8220;.vc_custom_1566918268179{margin-top: -40px !important;}&#8220;]\n<h1>REFERENZEN<\/h1>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/4&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/4&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text]\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/wilhelm-timm-fliesen.de\/referenzen\/\">HIGHLIGHTS<\/a><\/h3>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/4&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text]\n<h3 style=\"text-align: center;\">ALLE REFERENZEN<\/h3>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/4&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_gallery type=&#8220;image_grid&#8220; images=&#8220;706,705,392,393,394,395,396,397,398,399,400,401,402,403,404,405,406,407,408,409,411,412,413,414,415,416,417,418,419,420,421,422,423,424&#8243; layout=&#8220;4&#8243; masonry_style=&#8220;true&#8220; bypass_image_cropping=&#8220;true&#8220; item_spacing=&#8220;default&#8220; gallery_style=&#8220;7&#8243; load_in_animation=&#8220;fade_in_from_bottom&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; bg_image=&#8220;35&#8243; bg_position=&#8220;center center&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][divider line_type=&#8220;No Line&#8220;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":9,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-102","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/pages\/102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/comments?post=102"}],"version-history":[{"count":6,"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/pages\/102\/revisions"}],"predecessor-version":[{"id":708,"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/pages\/102\/revisions\/708"}],"up":[{"embeddable":true,"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/pages\/9"}],"wp:attachment":[{"href":"https:\/\/wilhelm-Timm-Fliesen.de\/index.php\/wp-json\/wp\/v2\/media?parent=102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}